{"id":5461,"date":"2023-07-06T17:17:30","date_gmt":"2023-07-06T09:17:30","guid":{"rendered":"https:\/\/keelungpass.com\/?page_id=5461"},"modified":"2023-11-17T15:12:53","modified_gmt":"2023-11-17T07:12:53","slug":"route3-en","status":"publish","type":"page","link":"https:\/\/keelungpass.com\/english\/route3-en\/","title":{"rendered":"route3 Badouzi Fishing Village(en)"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"5461\" class=\"elementor elementor-5461\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-gloeuac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"gloeuac\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-04f1335\" data-id=\"04f1335\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26634d7 elementor-widget elementor-widget-heading\" data-id=\"26634d7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\ud83c\udfa3\ud83c\udfa3Badouzi Fishing Village Walk\ud83c\udfa3\ud83c\udfa3<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6ba605 elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"f6ba605\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay_speed&quot;:10000,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f6ba605\" data-elementor-lightbox-title=\"\u6d77\u79d1\u9928\u8207\u516b\u6597\u5b50\u80cc\u666f\u4ecb\u7d39\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzA3OCwidXJsIjoiaHR0cHM6XC9cL2tlZWx1bmdwYXNzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDdcL1x1NmQ3N1x1NzlkMVx1OTkyOFx1ODIwN1x1NTE2Ylx1NjU5N1x1NWI1MFx1ODBjY1x1NjY2Zlx1NGVjYlx1N2QzOS5wbmciLCJzbGlkZXNob3ciOiJmNmJhNjA1In0%3D\" href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u6d77\u79d1\u9928\u8207\u516b\u6597\u5b50\u80cc\u666f\u4ecb\u7d39.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u6d77\u79d1\u9928\u8207\u516b\u6597\u5b50\u80cc\u666f\u4ecb\u7d39-150x150.png\" alt=\"\u6d77\u79d1\u9928\u8207\u516b\u6597\u5b50\u80cc\u666f\u4ecb\u7d39\" title=\"\"><figcaption class=\"elementor-image-carousel-caption\">\u6d77\u79d1\u9928\u8207\u516b\u6597\u5b50\u80cc\u666f\u4ecb\u7d39<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f6ba605\" data-elementor-lightbox-title=\"\u85cd\u6d77\u5de5\u4f5c\u574a\u4ecb\u7d39\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzA3OSwidXJsIjoiaHR0cHM6XC9cL2tlZWx1bmdwYXNzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDdcL1x1ODVjZFx1NmQ3N1x1NWRlNVx1NGY1Y1x1NTc0YVx1NGVjYlx1N2QzOS5qcGciLCJzbGlkZXNob3ciOiJmNmJhNjA1In0%3D\" href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u85cd\u6d77\u5de5\u4f5c\u574a\u4ecb\u7d39.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u85cd\u6d77\u5de5\u4f5c\u574a\u4ecb\u7d39-150x150.jpg\" alt=\"\u85cd\u6d77\u5de5\u4f5c\u574a\u4ecb\u7d39\" title=\"\"><figcaption class=\"elementor-image-carousel-caption\">\u85cd\u6d77\u5de5\u4f5c\u574a\u4ecb\u7d39<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f6ba605\" data-elementor-lightbox-title=\"~\ud83c\udf60\u85af\u6994\u67d3DIY~\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzA4MCwidXJsIjoiaHR0cHM6XC9cL2tlZWx1bmdwYXNzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDdcL1x1ZDgzY1x1ZGY2MFx1ODVhZlx1Njk5NFx1NjdkM0RJWS5qcGciLCJzbGlkZXNob3ciOiJmNmJhNjA1In0%3D\" href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\ud83c\udf60\u85af\u6994\u67d3DIY.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\ud83c\udf60\u85af\u6994\u67d3DIY-150x150.jpg\" alt=\"~\ud83c\udf60\u85af\u6994\u67d3DIY~\" title=\"\"><figcaption class=\"elementor-image-carousel-caption\">~\ud83c\udf60\u85af\u6994\u67d3DIY~<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f6ba605\" data-elementor-lightbox-title=\"~\ud83e\udd91\u4e00\u591c\u5e72DIY\uff5e\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzA4OCwidXJsIjoiaHR0cHM6XC9cL2tlZWx1bmdwYXNzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDdcL1x1ZDgzZVx1ZGQ5MVx1NGUwMFx1NTkxY1x1NWU3MkRJWVx1ZmY1ZS5qcGciLCJzbGlkZXNob3ciOiJmNmJhNjA1In0%3D\" href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\ud83e\udd91\u4e00\u591c\u5e72DIY\uff5e.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\ud83e\udd91\u4e00\u591c\u5e72DIY\uff5e-150x150.jpg\" alt=\"~\ud83e\udd91\u4e00\u591c\u5e72DIY\uff5e\" title=\"\"><figcaption class=\"elementor-image-carousel-caption\">~\ud83e\udd91\u4e00\u591c\u5e72DIY\uff5e<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f6ba605\" data-elementor-lightbox-title=\"\u563f\u8def\u5cf6\u6c11\u4ecb\u7d39\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzA4MiwidXJsIjoiaHR0cHM6XC9cL2tlZWx1bmdwYXNzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDdcL1x1NTYzZlx1OGRlZlx1NWNmNlx1NmMxMVx1NGVjYlx1N2QzOS5wbmciLCJzbGlkZXNob3ciOiJmNmJhNjA1In0%3D\" href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u563f\u8def\u5cf6\u6c11\u4ecb\u7d39.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u563f\u8def\u5cf6\u6c11\u4ecb\u7d39-150x150.png\" alt=\"\u563f\u8def\u5cf6\u6c11\u4ecb\u7d39\" title=\"\"><figcaption class=\"elementor-image-carousel-caption\">\u563f\u8def\u5cf6\u6c11\u4ecb\u7d39<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f6ba605\" data-elementor-lightbox-title=\"~\u98db\u9b5a\u5375\u9999\u8178DIY~\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzA4NywidXJsIjoiaHR0cHM6XC9cL2tlZWx1bmdwYXNzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDdcL1x1OThkYlx1OWI1YVx1NTM3NVx1OTk5OVx1ODE3OERJWS0xLmpwZyIsInNsaWRlc2hvdyI6ImY2YmE2MDUifQ%3D%3D\" href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u98db\u9b5a\u5375\u9999\u8178DIY-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u98db\u9b5a\u5375\u9999\u8178DIY-1-150x150.jpg\" alt=\"~\u98db\u9b5a\u5375\u9999\u8178DIY~\" title=\"\"><figcaption class=\"elementor-image-carousel-caption\">~\u98db\u9b5a\u5375\u9999\u8178DIY~<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f6ba605\" data-elementor-lightbox-title=\"\u6f01\u6751\u5c0e\u89bd\u8207\u6d77\u8c79\u5ca9\u8349\u978b\u9ad4\u9a57\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzA4OSwidXJsIjoiaHR0cHM6XC9cL2tlZWx1bmdwYXNzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDdcL1x1NmYwMVx1Njc1MVx1NWMwZVx1ODliZFx1ODIwN1x1NmQ3N1x1OGM3OVx1NWNhOVx1ODM0OVx1OTc4Ylx1OWFkNFx1OWE1Ny5qcGciLCJzbGlkZXNob3ciOiJmNmJhNjA1In0%3D\" href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u6f01\u6751\u5c0e\u89bd\u8207\u6d77\u8c79\u5ca9\u8349\u978b\u9ad4\u9a57.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u6f01\u6751\u5c0e\u89bd\u8207\u6d77\u8c79\u5ca9\u8349\u978b\u9ad4\u9a57-150x150.jpg\" alt=\"\u6f01\u6751\u5c0e\u89bd\u8207\u6d77\u8c79\u5ca9\u8349\u978b\u9ad4\u9a57\" title=\"\"><figcaption class=\"elementor-image-carousel-caption\">\u6f01\u6751\u5c0e\u89bd\u8207\u6d77\u8c79\u5ca9\u8349\u978b\u9ad4\u9a57<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 8\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"f6ba605\" data-elementor-lightbox-title=\"\u516b\u6597\u5b50\u5176\u4ed6\u8cc7\u8a0a\u88dc\u5145\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzA5MCwidXJsIjoiaHR0cHM6XC9cL2tlZWx1bmdwYXNzLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDdcL1x1NTE2Ylx1NjU5N1x1NWI1MFx1NTE3Nlx1NGVkNlx1OGNjN1x1OGEwYVx1ODhkY1x1NTE0NS5wbmciLCJzbGlkZXNob3ciOiJmNmJhNjA1In0%3D\" href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u5176\u4ed6\u8cc7\u8a0a\u88dc\u5145.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u5176\u4ed6\u8cc7\u8a0a\u88dc\u5145-150x150.png\" alt=\"\u516b\u6597\u5b50\u5176\u4ed6\u8cc7\u8a0a\u88dc\u5145\" title=\"\"><figcaption class=\"elementor-image-carousel-caption\">\u516b\u6597\u5b50\u5176\u4ed6\u8cc7\u8a0a\u88dc\u5145<\/figcaption><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b5db54e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b5db54e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb897df\" data-id=\"cb897df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9859630 elementor-widget elementor-widget-menu-anchor\" data-id=\"9859630\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"turnbackpartBZ\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f19656 elementor-widget elementor-widget-accordion\" data-id=\"7f19656\" data-element_type=\"widget\" id=\"part3\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1331\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1331\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Part1. Introduction to Badouzi & National Museum of Marine Science and Technology (Haikeguan)<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<div id=\"elementor-tab-content-1331\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1331\"><p>\u00a0<\/p><ol><li><a href=\"#BZpart1\">Transportation to National Museum of Marine Science and Technology<\/a><\/li><li><a href=\"#BZpart1\">History of Badouzi Fishing Port<\/a><\/li><li><a href=\"#BZpart1\">The Rise and Fall History of Badouzi Fishing Harbor<\/a><\/li><li><a href=\"#BZpart1\">Background of the Establishment of the National Museum of Marine\u00a0 Science and Technology<\/a><\/li><li><a href=\"#BZpart1\">Internal Functions of the Museum, Part 1<\/a><\/li><li><a href=\"#BZpart1\">Internal Functions of the Museum, Part 2<\/a><\/li><li><a href=\"#BZpart1\">Panda Story<\/a><\/li><\/ol><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1332\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1332\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Part2. Blue Sea Workshop<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<div id=\"elementor-tab-content-1332\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1332\"><ol><li><a href=\"#BZpart2\">The meaning of the name of Blue Sea Workshop<\/a><\/li><li><a href=\"#BZpart2\">Location and Description<\/a><\/li><li><a href=\"#BZpart2\">Introduction of the Founder and Philosophy<\/a><\/li><li><a href=\"#BZpart2\">Overview of the main project services provided<\/a><\/li><li><a href=\"#BZpart2\">The origin of Shoulang Yam Sea-dyeing<\/a><\/li><li><a href=\"#BZpart2\">Introduction to Shoulang Yam<\/a><\/li><\/ol><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1333\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1333\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Part2-1. ~Shoulang-Yam Sea-dyeing DIY~<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<div id=\"elementor-tab-content-1333\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1333\"><ol><li><a href=\"#2-1DIY\">Tying method 1:Cloud patterns<\/a><\/li><li><a href=\"#2-1DIY\">Tying method2:fish scale pattern<\/a><\/li><li><a href=\"#2-1DIY\">Tying method3:regular triangle pattern<\/a><\/li><li><a href=\"#2-1DIY\">Dip the cloth into the boiled Shoulang yam juice to dye it.<\/a><\/li><li><a href=\"#2-1DIY\">Take the dyed fabric to the bench for cleaning.<\/a><\/li><li><a href=\"#2-1DIY\">Mission accomplished after drying.<\/a><\/li><\/ol><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1334\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1334\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Part2-2. ~Semi-dried (fish) DIY\uff5e<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<div id=\"elementor-tab-content-1334\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1334\"><ol><li><a href=\"#2-2DIY\">Semi-dried (fish) introduction<\/a><\/li><li><a href=\"#2-2DIY\">Cut open to remove internal organs and soak in salt water<\/a><\/li><li><a href=\"#2-2DIY\">Hanging and Air Drying the squid completed<\/a><\/li><\/ol><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1335\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1335\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Part3. HaloPataw<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<div id=\"elementor-tab-content-1335\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1335\"><p>\u00a0<\/p><ol><li><a href=\"#BZpart3\">HaloPataw Meaning<\/a><\/li><li><a href=\"#BZpart3\">Halopataw Location and Description<\/a><\/li><li><a href=\"#BZpart3\">Introduction of the Founder<\/a><\/li><li><a href=\"#BZpart3\">Main Services Provided<\/a><\/li><li><a href=\"#BZpart3\">Sun-dried Flying Fish Eggs<\/a><\/li><li><a href=\"#BZpart3\">History of Flying Fish Roe Sausage Packaging Improvement<\/a><\/li><li><a href=\"#BZpart3\">Porkson Food Flying Fish Roe Sausage Sales Information<\/a><\/li><\/ol><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1336\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1336\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Part3-1. ~Flying Fish Roe Sausage DIY~<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<div id=\"elementor-tab-content-1336\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1336\"><p>\u00a0<\/p><ol><li><a href=\"#3-1DIY\">Ingredients for Flying Fish Roe Sausage<\/a><\/li><li><a href=\"#3-1DIY\">Step 1: Put the casings on the needle<\/a><\/li><li><a href=\"#3-1DIY\">Step 2: Put the stuffing into the syringe<\/a><\/li><li><a href=\"#3-1DIY\">Step 3: Decide on the shape of the sausage<\/a><\/li><li><a href=\"#3-1DIY\">Sausage Aging Room<\/a><\/li><li><a href=\"#3-1DIY\">Packaging the sausage after aging is completed<\/a><\/li><\/ol><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1337\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1337\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Part4. Fishing Village Guided Tour and Straw Shoe Experience<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<div id=\"elementor-tab-content-1337\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1337\"><p>\u00a0<\/p><ol><li><a href=\"#BZpart4\">Sedimentary Rock Houses and Coral Reef Houses<\/a><\/li><li><a href=\"#BZpart4\">The Du Family, a Large Clan in Badouzi, and Local Issues<\/a><\/li><li><a href=\"#BZpart4\">The Legend of DuTian Temple and Mazu&#8217;s Arrival<\/a><\/li><li><a href=\"#BZpart4\">Charging Room for Fishing Lanterns<\/a><\/li><li><a href=\"#BZpart4\">Traditional Fishing Village Life<\/a><\/li><li><a href=\"#BZpart4\">Daping shore<\/a><\/li><li><a href=\"#BZpart4\">Start exploring with straw sandals<\/a><\/li><li><a href=\"#BZpart4\">Gelidium<\/a><\/li><li><a href=\"#BZpart4\">Seal Rock<\/a><\/li><li><a href=\"#BZpart4\">Return Transportation Guide<\/a><\/li><\/ol><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1338\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1338\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Part5. Additional information about Badouzi<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<div id=\"elementor-tab-content-1338\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1338\"><p>\u00a0<\/p><ol><li><a href=\"#BZpart5\">Badouzi&#8217;s Delicious Restaurant &#8211; Introduction to Chunxing Dumpling<\/a><\/li><li><a href=\"#BZpart5\">Badouzi Night Market<\/a><\/li><li><a href=\"#BZpart5\">Wang-yo Valley<\/a><\/li><li><a href=\"#BZpart5\">Chaojing Park<\/a><\/li><li><a href=\"#BZpart5\">The Chaojing Bay Festival<\/a><\/li><li><a href=\"#BZpart5\">Shen-Ao Rail<span style=\"font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-kerning: auto; font-optical-sizing: auto; font-feature-settings: normal; font-variation-settings: normal; font-variant-position: normal; font-stretch: normal; font-size: 7pt; line-height: normal; font-family: 'Times New Roman';\">\u00a0<\/span><span lang=\"EN-US\" style=\"font-style: inherit; font-weight: inherit; text-indent: -18pt; background-color: var(--ast-global-color-5); font-size: 14pt; font-family: Calibri, sans-serif; color: black;\">Bike<\/span><\/a><br \/><p style=\"text-indent: -18.0pt; mso-list: l0 level1 lfo1; margin: 0cm 0cm .0001pt 18.0pt;\">\u00a0<\/p><\/li><\/ol><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-143e6c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"143e6c4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6810119\" data-id=\"6810119\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e9f630 elementor-widget elementor-widget-menu-anchor\" data-id=\"6e9f630\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"BZpart1\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34a04a9 elementor-widget elementor-widget-text-editor\" data-id=\"34a04a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\"><img decoding=\"async\" class=\"emoji aligncenter\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/2600.svg\" alt=\"\u2600\" title=\"\">Part1. Introduction to Badouzi &amp; National Museum of Marine Science and Technology (Haikeguan)<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fdf82f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdf82f0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8e2168e\" data-id=\"8e2168e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e54b19d elementor-widget elementor-widget-heading\" data-id=\"e54b19d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1.Transportation to National Museum of Marine Science and Technology\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dd243b5\" data-id=\"dd243b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ac10b0 elementor-widget elementor-widget-heading\" data-id=\"8ac10b0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2.History of Badouzi Fishing Port\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fc5bf8e\" data-id=\"fc5bf8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19ef005 elementor-widget elementor-widget-heading\" data-id=\"19ef005\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.The Rise and Fall History of Badouzi Fishing Harbor<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b06cc5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b06cc5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7279608\" data-id=\"7279608\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1017c6 elementor-widget elementor-widget-text-editor\" data-id=\"b1017c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-6580 aligncenter\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-6-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-6-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-6-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-6-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-6-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-6-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-6.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b504.mp3?_=1\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b504.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b504.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-220e549\" data-id=\"220e549\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14e3b72 elementor-widget elementor-widget-text-editor\" data-id=\"14e3b72\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-6584\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-5-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-5-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-5-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-5-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-5-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-5-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-5.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h5><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-2\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b505.mp3?_=2\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b505.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b505.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-58efa03\" data-id=\"58efa03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f83dde3 elementor-widget elementor-widget-text-editor\" data-id=\"f83dde3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6588\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-5-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-5-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-5-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-5-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-5-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-5-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-5.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-3\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5061.mp3?_=3\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5061.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5061.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8b9822 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8b9822\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-150a7af\" data-id=\"150a7af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b12ad0f elementor-widget elementor-widget-heading\" data-id=\"b12ad0f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4.Background of the Establishment of the National Museum of Marine  Science and Technology<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7f4fde0\" data-id=\"7f4fde0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15cbb79 elementor-widget elementor-widget-heading\" data-id=\"15cbb79\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5.Internal Functions of the Museum (1)\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a924348\" data-id=\"a924348\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cc76f4 elementor-widget elementor-widget-heading\" data-id=\"4cc76f4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6.Internal Functions of the Museum (2)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-882eea5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"882eea5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c3b53e1\" data-id=\"c3b53e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41a5ee1 elementor-widget elementor-widget-text-editor\" data-id=\"41a5ee1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6593\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/24-1-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/24-1-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/24-1-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/24-1-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/24-1-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/24-1-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/24-1.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h5><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-4\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b507.mp3?_=4\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b507.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b507.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5326c12\" data-id=\"5326c12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecf0627 elementor-widget elementor-widget-text-editor\" data-id=\"ecf0627\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6597\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-5-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-5-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-5-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-5-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-5-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-5-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-5.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-5\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b508.mp3?_=5\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b508.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b508.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e1cb7f5\" data-id=\"e1cb7f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0745bf elementor-widget elementor-widget-text-editor\" data-id=\"b0745bf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6601\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-5-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-5-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-5-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-5-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-5-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-5-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-5.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-6\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b509.mp3?_=6\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b509.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b509.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45cae7e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45cae7e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2eef615\" data-id=\"2eef615\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42b9397 elementor-widget elementor-widget-heading\" data-id=\"42b9397\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">7. Panda Story<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7ba9fdc\" data-id=\"7ba9fdc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-228d79f\" data-id=\"228d79f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e1ba69b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e1ba69b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-120d2d4\" data-id=\"120d2d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1aaebf8 elementor-widget elementor-widget-text-editor\" data-id=\"1aaebf8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6605\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-5-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-5-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-5-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-5-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-5-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-5-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-5.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-7\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5010.mp3?_=7\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5010.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5010.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-62a63fa\" data-id=\"62a63fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e203d24\" data-id=\"e203d24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf735d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf735d8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f24d95\" data-id=\"6f24d95\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3192ad elementor-align-right elementor-widget elementor-widget-button\" data-id=\"e3192ad\" data-element_type=\"widget\" id=\"turn back part BZ\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Return to playlist<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0cf46c4 elementor-widget elementor-widget-spacer\" data-id=\"0cf46c4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11c755f elementor-widget elementor-widget-menu-anchor\" data-id=\"11c755f\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"BZpart2\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c17ffbf elementor-widget elementor-widget-text-editor\" data-id=\"c17ffbf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\"><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/2600.svg\" alt=\"\u2600\" title=\"\">Part2. Blue Sea workshop<\/h2><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0748a79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0748a79\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e0b50c1\" data-id=\"e0b50c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-269d03f elementor-widget elementor-widget-heading\" data-id=\"269d03f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1. Bluesea workshop<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6257142\" data-id=\"6257142\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4251a99 elementor-widget elementor-widget-heading\" data-id=\"4251a99\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. Location and Description<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8b4779e\" data-id=\"8b4779e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1963c9 elementor-widget elementor-widget-heading\" data-id=\"a1963c9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.Introduction of the Founder <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c783afc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c783afc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-75d3225\" data-id=\"75d3225\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0170108 elementor-widget elementor-widget-text-editor\" data-id=\"0170108\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6618\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-8\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5012.mp3?_=8\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5012.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5012.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-11bdd2c\" data-id=\"11bdd2c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5d03a8 elementor-widget elementor-widget-text-editor\" data-id=\"c5d03a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6614\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-5-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-5-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-5-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-5-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-5-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-5-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-5.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-9\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5013.mp3?_=9\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5013.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5013.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ebaa8d9\" data-id=\"ebaa8d9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6ecd1f elementor-widget elementor-widget-text-editor\" data-id=\"a6ecd1f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6628\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-4-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-4-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-4-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-4-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-4-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-4-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-4.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-10\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5014.mp3?_=10\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5014.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5014.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0958389 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0958389\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b4279e2\" data-id=\"b4279e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-734e7a0 elementor-widget elementor-widget-heading\" data-id=\"734e7a0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4.The main services\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dde017d\" data-id=\"dde017d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abe59ec elementor-widget elementor-widget-heading\" data-id=\"abe59ec\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5. Shoulang Yam Sea-dyeing<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4b6771a\" data-id=\"4b6771a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f62313 elementor-widget elementor-widget-heading\" data-id=\"8f62313\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6. Shoulang Yam<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-727ee98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"727ee98\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-21441c0\" data-id=\"21441c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8212d0d elementor-widget elementor-widget-text-editor\" data-id=\"8212d0d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7074\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-5-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-5-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-5-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-5-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-5-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-5-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-5.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-11\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5015.mp3?_=11\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5015.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5015.mp3<\/a><\/audio><\/p><p style=\"text-align: center;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0a1a8e1\" data-id=\"0a1a8e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-428d0c7 elementor-widget elementor-widget-text-editor\" data-id=\"428d0c7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6759 aligncenter\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-2-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-2-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-2-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-2-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-2-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-2-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-2.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-12\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5016.mp3?_=12\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5016.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5016.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-54b5913\" data-id=\"54b5913\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94e84b8 elementor-widget elementor-widget-text-editor\" data-id=\"94e84b8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6642\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-3-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-3-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-3-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-3-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-3-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-3-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-3.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-13\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5017.mp3?_=13\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5017.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5017.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aab9658 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aab9658\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eebde4f\" data-id=\"eebde4f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aea39d3 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"aea39d3\" data-element_type=\"widget\" id=\"turn back part BZ\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Return to playlist<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1057e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1057e2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66bce6e\" data-id=\"66bce6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-688cf31 elementor-widget elementor-widget-menu-anchor\" data-id=\"688cf31\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"2-1DIY\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17940b7 elementor-widget elementor-widget-heading\" data-id=\"17940b7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><img decoding=\"async\" class=\"emoji\" role=\"img\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/2600.svg\" alt=\"\u2600\" style=\"color: var(--ast-global-color-2);font-size: 1.76471rem;font-style: inherit\" title=\"\">Part2-1.~\ud83c\udf60Shoulang Yam\nSea-dyeing DIY~<br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5085fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5085fc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cb2ae4f\" data-id=\"cb2ae4f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d9d518 elementor-widget elementor-widget-heading\" data-id=\"0d9d518\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">7. Tying method 1:\nCloud patterns\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8d13a46\" data-id=\"8d13a46\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1aa44b3 elementor-widget elementor-widget-heading\" data-id=\"1aa44b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">8. Tying method2:fish scale pattern<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f302cc2\" data-id=\"f302cc2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-925c445 elementor-widget elementor-widget-heading\" data-id=\"925c445\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">9.Tying method3:regular triangle pattern<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-268c631 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"268c631\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-11f7d5e\" data-id=\"11f7d5e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98541e0 elementor-widget elementor-widget-text-editor\" data-id=\"98541e0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7189\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-8-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-8-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-8-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-8-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-8-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-8-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-8.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-14\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5019.mp3?_=14\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5019.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5019.mp3<\/a><\/audio><\/p><p style=\"text-align: center;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ef7523c\" data-id=\"ef7523c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a9c724 elementor-widget elementor-widget-text-editor\" data-id=\"5a9c724\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7190\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/11-5-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/11-5-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/11-5-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/11-5-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/11-5-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/11-5-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/11-5.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-15\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5020.mp3?_=15\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5020.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5020.mp3<\/a><\/audio><\/p><p style=\"text-align: center;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-02f2102\" data-id=\"02f2102\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06bf43b elementor-widget elementor-widget-text-editor\" data-id=\"06bf43b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7198\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-6-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-6-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-6-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-6-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-6-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-6-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-6.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-16\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5021.mp3?_=16\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5021.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5021.mp3<\/a><\/audio><\/p><p style=\"text-align: center;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f29b89 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f29b89\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-04e78a9\" data-id=\"04e78a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0a334d elementor-widget elementor-widget-heading\" data-id=\"e0a334d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">10.Dip the cloth into the boiled Shoulang yam juice to dye it<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1a6bc77\" data-id=\"1a6bc77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffe51b3 elementor-widget elementor-widget-heading\" data-id=\"ffe51b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">11.Take the dyed fabric to the bench for cleaning<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1bdb6c8\" data-id=\"1bdb6c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e1e83a elementor-widget elementor-widget-heading\" data-id=\"6e1e83a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">12.Mission accomplished after drying<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-209f112 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"209f112\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ed62d43\" data-id=\"ed62d43\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-109dd31 elementor-widget elementor-widget-text-editor\" data-id=\"109dd31\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6695\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/16-2-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/16-2-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/16-2-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/16-2-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/16-2-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/16-2-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/16-2.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-17\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5022.mp3?_=17\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5022.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5022.mp3<\/a><\/audio><\/p><p style=\"text-align: center;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-879bcb0\" data-id=\"879bcb0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4af5e2f elementor-widget elementor-widget-text-editor\" data-id=\"4af5e2f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6700\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/18-1-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/18-1-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/18-1-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/18-1-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/18-1-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/18-1-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/18-1.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-18\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5023.mp3?_=18\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5023.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5023.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4a1e4c7\" data-id=\"4a1e4c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1baa3b elementor-widget elementor-widget-text-editor\" data-id=\"f1baa3b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6701\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/19-1-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/19-1-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/19-1-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/19-1-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/19-1-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/19-1-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/19-1.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-19\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5024.mp3?_=19\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5024.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5024.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4681db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4681db\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a70f4d2\" data-id=\"a70f4d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65dfdb1 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"65dfdb1\" data-element_type=\"widget\" id=\"turn back part BZ\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Return to playlist<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ee23da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ee23da\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-baa185c\" data-id=\"baa185c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0627935 elementor-widget elementor-widget-menu-anchor\" data-id=\"0627935\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"2-2DIY\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a343a3 elementor-widget elementor-widget-heading\" data-id=\"3a343a3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><img decoding=\"async\" class=\"emoji\" role=\"img\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/2600.svg\" alt=\"\u2600\" style=\"color: var(--ast-global-color-2);font-size: 1.76471rem;font-style: inherit\" title=\"\">Part2-2.~\ud83e\udd91Semi-dried (fish)<span lang=\"EN-US\" style=\"font-size:14.0pt;font-family:&quot;Calibri&quot;,sans-serif;color:black\"> <\/span>DIY\uff5e<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab2c0ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab2c0ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9916c60\" data-id=\"9916c60\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5732b9a elementor-widget elementor-widget-heading\" data-id=\"5732b9a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">14. practice of drying and salting Squid<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f87da28\" data-id=\"f87da28\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfe02bc elementor-widget elementor-widget-heading\" data-id=\"cfe02bc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">15.Cut open to remove internal organs and soak in salt water<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6310720\" data-id=\"6310720\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0f874f elementor-widget elementor-widget-heading\" data-id=\"c0f874f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">16.Hanging and Air Drying the squid completed<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3df5fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3df5fc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0e71ee5\" data-id=\"0e71ee5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42204a3 elementor-widget elementor-widget-text-editor\" data-id=\"42204a3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6711\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/21-1-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/21-1-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/21-1-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/21-1-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/21-1-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/21-1-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/21-1.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-20\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5025.mp3?_=20\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5025.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5025.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d4e7acb\" data-id=\"d4e7acb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27361cf elementor-widget elementor-widget-text-editor\" data-id=\"27361cf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6715\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/20-1-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/20-1-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/20-1-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/20-1-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/20-1-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/20-1-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/20-1.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-21\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5026.mp3?_=21\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5026.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5026.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ce8dc20\" data-id=\"ce8dc20\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-759f9e3 elementor-widget elementor-widget-text-editor\" data-id=\"759f9e3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6719\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/22-1-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/22-1-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/22-1-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/22-1-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/22-1-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/22-1-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/22-1.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-22\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5027.mp3?_=22\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5027.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5027.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c994794 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c994794\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c697416\" data-id=\"c697416\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ee8e01 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"7ee8e01\" data-element_type=\"widget\" id=\"turn back part BZ\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Return to playlist<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-09d4b8f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"09d4b8f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ed9581\" data-id=\"3ed9581\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f72cf4 elementor-widget elementor-widget-menu-anchor\" data-id=\"4f72cf4\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"BZpart3\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d32f955 elementor-widget elementor-widget-heading\" data-id=\"d32f955\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><img decoding=\"async\" class=\"emoji\" role=\"img\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/2600.svg\" alt=\"\u2600\" style=\"color: var(--ast-global-color-2);font-size: 1.76471rem;font-style: inherit\" title=\"\">Part3. HaloPataw<span style=\"font-style: inherit;font-weight: inherit;color: var(--ast-global-color-2);font-size: 1.76471rem;background-color: var(--ast-global-color-5)\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f960924 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f960924\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5580c54\" data-id=\"5580c54\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95f3def elementor-widget elementor-widget-heading\" data-id=\"95f3def\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1.HaloPataw Meaning<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-35684c8\" data-id=\"35684c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c8eb2e elementor-widget elementor-widget-heading\" data-id=\"5c8eb2e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2.Halopataw Location and Description\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-35dc009\" data-id=\"35dc009\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddfcd5f elementor-widget elementor-widget-heading\" data-id=\"ddfcd5f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.Introduction of the Founder<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a687be elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a687be\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9a1d66b\" data-id=\"9a1d66b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bf4599 elementor-widget elementor-widget-text-editor\" data-id=\"0bf4599\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6792\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-7-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-7-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-7-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-7-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-7-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-7-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-7.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-23\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5029.mp3?_=23\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5029.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5029.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-da5e0db\" data-id=\"da5e0db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c8080e elementor-widget elementor-widget-text-editor\" data-id=\"1c8080e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6796\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-6-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-6-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-6-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-6-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-6-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-6-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-6.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-24\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5030.mp3?_=24\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5030.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5030.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e350969\" data-id=\"e350969\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e26593 elementor-widget elementor-widget-text-editor\" data-id=\"7e26593\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6800\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-6-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-6-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-6-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-6-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-6-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-6-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-6.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-25\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5031.mp3?_=25\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5031.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5031.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-946e66f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"946e66f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4f92b3a\" data-id=\"4f92b3a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc3e937 elementor-widget elementor-widget-heading\" data-id=\"cc3e937\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4. Main Services Provided<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1cb21e5\" data-id=\"1cb21e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-646ca9e elementor-widget elementor-widget-heading\" data-id=\"646ca9e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5.Sun-dried Flying Fish Eggs<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d9d0ca2\" data-id=\"d9d0ca2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f3eb96 elementor-widget elementor-widget-heading\" data-id=\"5f3eb96\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6.History of Flying Fish Roe Sausage Packaging Improvement<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52bbc7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52bbc7f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fd91f33\" data-id=\"fd91f33\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9312787 elementor-widget elementor-widget-text-editor\" data-id=\"9312787\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6804\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-6-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-6-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-6-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-6-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-6-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-6-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-6.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-26\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5032.mp3?_=26\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5032.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5032.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-52149ee\" data-id=\"52149ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aab1d8e elementor-widget elementor-widget-text-editor\" data-id=\"aab1d8e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6808\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-6-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-6-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-6-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-6-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-6-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-6-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-6.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-27\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5033.mp3?_=27\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5033.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5033.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1c8f105\" data-id=\"1c8f105\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ae1003 elementor-widget elementor-widget-text-editor\" data-id=\"7ae1003\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6868\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-3-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-3-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-3-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-3-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-3-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-3-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-3.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-28\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5040.mp3?_=28\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5040.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5040.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c0d676 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c0d676\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-61c40c1\" data-id=\"61c40c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-223fc6e elementor-widget elementor-widget-heading\" data-id=\"223fc6e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">7. Porkson Food Flying Fish Roe Sausage Sales Information<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-72fe9a0\" data-id=\"72fe9a0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-59944dd\" data-id=\"59944dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40543e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40543e5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-053b724\" data-id=\"053b724\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec54663 elementor-widget elementor-widget-text-editor\" data-id=\"ec54663\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6879\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-1-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-1-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-1-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-1-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-1-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-1-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-1.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-29\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5041.mp3?_=29\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5041.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5041.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1910eae\" data-id=\"1910eae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-35d0538\" data-id=\"35d0538\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8982566 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8982566\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f6cac52\" data-id=\"f6cac52\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bef1602 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"bef1602\" data-element_type=\"widget\" id=\"turn back part BZ\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Return to playlist<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-826e09f elementor-widget elementor-widget-menu-anchor\" data-id=\"826e09f\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"3-1DIY\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b6a659 elementor-widget elementor-widget-heading\" data-id=\"9b6a659\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><img decoding=\"async\" class=\"emoji\" role=\"img\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/2600.svg\" alt=\"\u2600\" style=\"color: var(--ast-global-color-2);font-size: 1.76471rem;font-style: inherit\" title=\"\">Part3-1.~Flying Fish Roe SausageDIY~<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42e2ec4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42e2ec4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e39b823\" data-id=\"e39b823\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4195215 elementor-widget elementor-widget-heading\" data-id=\"4195215\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6.Ingredients for Flying Fish Roe Sausage<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-bdbdf0c\" data-id=\"bdbdf0c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b50cf6 elementor-widget elementor-widget-heading\" data-id=\"8b50cf6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">7. Step 1: Put the casings on the needle<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-985d01c\" data-id=\"985d01c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-158864e elementor-widget elementor-widget-heading\" data-id=\"158864e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">8. Step 2: Put the stuffing into the syringe<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f3c8eff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f3c8eff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e2a2b7b\" data-id=\"e2a2b7b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08e63fe elementor-widget elementor-widget-text-editor\" data-id=\"08e63fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6815\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-6-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-6-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-6-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-6-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-6-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-6-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-6.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-30\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5034.mp3?_=30\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5034.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5034.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3a3336b\" data-id=\"3a3336b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c85a27 elementor-widget elementor-widget-text-editor\" data-id=\"1c85a27\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6819\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-4-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-4-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-4-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-4-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-4-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-4-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-4.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-31\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5035.mp3?_=31\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5035.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5035.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f6e2ea0\" data-id=\"f6e2ea0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c8bc4b elementor-widget elementor-widget-text-editor\" data-id=\"4c8bc4b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6826\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-6-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-6-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-6-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-6-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-6-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-6-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-6.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-32\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5036.mp3?_=32\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5036.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5036.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-664a660 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"664a660\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cf9ad87\" data-id=\"cf9ad87\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4ada8e elementor-widget elementor-widget-heading\" data-id=\"e4ada8e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">9. Step 3: Decide on the shape of the sausage<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1d07c31\" data-id=\"1d07c31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc0c0e2 elementor-widget elementor-widget-heading\" data-id=\"dc0c0e2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">10.Sausage Aging Room\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5dbe345\" data-id=\"5dbe345\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33ecc37 elementor-widget elementor-widget-heading\" data-id=\"33ecc37\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">11.Packaging the sausage after aging is completed\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab9e1f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab9e1f1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d5957a9\" data-id=\"d5957a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2d1e8e elementor-widget elementor-widget-text-editor\" data-id=\"c2d1e8e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6830\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-5-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-5-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-5-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-5-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-5-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-5-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-5.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-33\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5037.mp3?_=33\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5037.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5037.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7e37fa9\" data-id=\"7e37fa9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c2a03d elementor-widget elementor-widget-text-editor\" data-id=\"0c2a03d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6834\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-6-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-6-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-6-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-6-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-6-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-6-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/10-6.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-34\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5038.mp3?_=34\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5038.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5038.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d82af50\" data-id=\"d82af50\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf9ec77 elementor-widget elementor-widget-text-editor\" data-id=\"bf9ec77\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6838\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-4-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-4-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-4-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-4-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-4-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-4-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/12-4.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-35\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5039.mp3?_=35\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5039.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5039.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9a5280 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9a5280\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d53dbac\" data-id=\"d53dbac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08b0893 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"08b0893\" data-element_type=\"widget\" id=\"turn back part BZ\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Return to playlist<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5193683 elementor-widget elementor-widget-menu-anchor\" data-id=\"5193683\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"BZpart4\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f14b33d elementor-widget elementor-widget-text-editor\" data-id=\"f14b33d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\"><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/2600.svg\" alt=\"\u2600\" title=\"\">Part4. Fishing Village Guided Tour and Straw Shoe Experience<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47867ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47867ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2a354c1\" data-id=\"2a354c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4e70db elementor-widget elementor-widget-heading\" data-id=\"b4e70db\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1.Sedimentary Rock Houses <br>and Coral Reef Houses<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ecd84a5\" data-id=\"ecd84a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-162ca1b elementor-widget elementor-widget-heading\" data-id=\"162ca1b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. The Du Family, a Large Clan<br> in Badouzi, and Local Issues\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-34355da\" data-id=\"34355da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07d6871 elementor-widget elementor-widget-heading\" data-id=\"07d6871\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.The Legend of DuTian Temple <br>and Mazu's Arrival<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d84515 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d84515\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ee2358e\" data-id=\"ee2358e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-103fdcc elementor-widget elementor-widget-text-editor\" data-id=\"103fdcc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6939\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-8-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-8-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-8-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-8-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-8-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-8-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/1-8.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-36\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5043.mp3?_=36\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5043.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5043.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-accf59c\" data-id=\"accf59c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f00093 elementor-widget elementor-widget-text-editor\" data-id=\"8f00093\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6943\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-7-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-7-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-7-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-7-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-7-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-7-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-7.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-37\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5044.mp3?_=37\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5044.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5044.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cda57b3\" data-id=\"cda57b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c064492 elementor-widget elementor-widget-text-editor\" data-id=\"c064492\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6944\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-7-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-7-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-7-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-7-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-7-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-7-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-7.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-38\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5045.mp3?_=38\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5045.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5045.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a48ec81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a48ec81\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cb4c074\" data-id=\"cb4c074\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d2eb99 elementor-widget elementor-widget-heading\" data-id=\"3d2eb99\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4. Charging Room for Fishing Lanterns<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cf263cf\" data-id=\"cf263cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79ab285 elementor-widget elementor-widget-heading\" data-id=\"79ab285\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5. Traditional Fishing Village Life<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d97c7c7\" data-id=\"d97c7c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb47ccc elementor-widget elementor-widget-heading\" data-id=\"bb47ccc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6. Daping shore<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a135730 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a135730\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d765151\" data-id=\"d765151\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-681fe77 elementor-widget elementor-widget-text-editor\" data-id=\"681fe77\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6948\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-7-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-7-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-7-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-7-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-7-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-7-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-7.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-39\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5046.mp3?_=39\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5046.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5046.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-75b4d32\" data-id=\"75b4d32\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-accfbfd elementor-widget elementor-widget-text-editor\" data-id=\"accfbfd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6952\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-7-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-7-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-7-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-7-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-7-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-7-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-7.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-40\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5047.mp3?_=40\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5047.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5047.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e239515\" data-id=\"e239515\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75607c2 elementor-widget elementor-widget-text-editor\" data-id=\"75607c2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6956\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-5-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-5-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-5-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-5-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-5-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-5-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-5.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-41\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5048.mp3?_=41\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5048.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5048.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-781f7c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"781f7c7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e7c5267\" data-id=\"e7c5267\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65d8559 elementor-widget elementor-widget-heading\" data-id=\"65d8559\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">7. Start exploring <br>with straw sandals<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0c81143\" data-id=\"0c81143\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc34098 elementor-widget elementor-widget-heading\" data-id=\"bc34098\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">8. Gelidium<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0e0825f\" data-id=\"0e0825f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d7f4fd elementor-widget elementor-widget-heading\" data-id=\"3d7f4fd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">9.Seal Rock<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7dde7d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7dde7d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0af7dbf\" data-id=\"0af7dbf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccd71dd elementor-widget elementor-widget-text-editor\" data-id=\"ccd71dd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6967\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-7-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-7-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-7-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-7-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-7-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-7-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/8-7.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-42\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5049.mp3?_=42\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5049.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5049.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-758802c\" data-id=\"758802c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c474b95 elementor-widget elementor-widget-text-editor\" data-id=\"c474b95\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6971\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-6-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-6-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-6-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-6-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-6-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-6-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/9-6.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-43\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5050.mp3?_=43\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5050.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5050.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-645b6c1\" data-id=\"645b6c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e256d20 elementor-widget elementor-widget-text-editor\" data-id=\"e256d20\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6979\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-4-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-4-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-4-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-4-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-4-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-4-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-4.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-44\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5051.mp3?_=44\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5051.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5051.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c3a5afc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c3a5afc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-52bec54\" data-id=\"52bec54\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8729ec0 elementor-widget elementor-widget-heading\" data-id=\"8729ec0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">10.Return Transportation Guide<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-31837d8\" data-id=\"31837d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e8d7835\" data-id=\"e8d7835\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6608802 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6608802\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-094d8de\" data-id=\"094d8de\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb19d97 elementor-widget elementor-widget-text-editor\" data-id=\"bb19d97\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6989\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-2-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-2-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-2-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-2-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-2-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-2-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b50\u7167\u7247\u7d71\u4e00\u5927\u5c0f-1-2.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-45\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5052.mp3?_=45\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5052.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5052.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2c7f5c5\" data-id=\"2c7f5c5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ecd1506\" data-id=\"ecd1506\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cce9e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cce9e8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a02610\" data-id=\"1a02610\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ced76a1 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"ced76a1\" data-element_type=\"widget\" id=\"turn back part BZ\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Return to playlist<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-316b009 elementor-widget elementor-widget-menu-anchor\" data-id=\"316b009\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"BZpart5\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4869965 elementor-widget elementor-widget-text-editor\" data-id=\"4869965\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\"><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/2600.svg\" alt=\"\u2600\" title=\"\">Part 5.Additional information about Badouzi<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9399e9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9399e9f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1860531\" data-id=\"1860531\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76c4d06 elementor-widget elementor-widget-text-editor\" data-id=\"76c4d06\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7044\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-7-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-7-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-7-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-7-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-7-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-7-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/2-7.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-46\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5055.mp3?_=46\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5055.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5055.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b659583\" data-id=\"b659583\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9964e5 elementor-widget elementor-widget-text-editor\" data-id=\"b9964e5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7048\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-8-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-8-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-8-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-8-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-8-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-8-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/3-8.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-47\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5056.mp3?_=47\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5056.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5056.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a2c1967\" data-id=\"a2c1967\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b40acb elementor-widget elementor-widget-text-editor\" data-id=\"1b40acb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7066\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-8-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-8-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-8-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-8-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-8-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-8-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/4-8.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-48\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5057.mp3?_=48\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5057.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5057.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e9013a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e9013a3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5c8f110\" data-id=\"5c8f110\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f3d0b8 elementor-widget elementor-widget-heading\" data-id=\"4f3d0b8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4.Chaojing Park<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b6b44c1\" data-id=\"b6b44c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cffd448 elementor-widget elementor-widget-heading\" data-id=\"cffd448\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5.The Chaojing Bay Festival<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b2fdb13\" data-id=\"b2fdb13\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-202609c elementor-widget elementor-widget-heading\" data-id=\"202609c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6.Shen-Ao Rail Bike<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9bc6626 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9bc6626\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d20b778\" data-id=\"d20b778\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d33f862 elementor-widget elementor-widget-text-editor\" data-id=\"d33f862\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7053\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-8-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-8-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-8-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-8-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-8-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-8-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/5-8.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-49\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5058.mp3?_=49\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5058.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5058.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6a1ccba\" data-id=\"6a1ccba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c60eb5f elementor-widget elementor-widget-text-editor\" data-id=\"c60eb5f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7054\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-8-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-8-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-8-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-8-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-8-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-8-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/6-8.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-50\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5059.mp3?_=50\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5059.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5059.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dbf635b\" data-id=\"dbf635b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24474b5 elementor-widget elementor-widget-text-editor\" data-id=\"24474b5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7058\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-6-300x210.png\" alt=\"\" width=\"300\" height=\"210\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-6-300x210.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-6-1024x717.png 1024w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-6-768x538.png 768w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-6-18x12.png 18w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-6-600x420.png 600w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/7-6.png 1181w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p style=\"text-align: center;\"><span style=\"background-color: var(--ast-global-color-5); color: var(--ast-global-color-3); font-size: 16px;\"><img decoding=\"async\" class=\"alignnone wp-image-12721\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png\" alt=\"\" width=\"20\" height=\"20\" title=\"\" srcset=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-150x150.png 150w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-300x300.png 300w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-12x12.png 12w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play-100x100.png 100w, https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/10\/play.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>Listen to audio guide<\/span>\uff1a<\/p><p><audio class=\"wp-audio-shortcode\" id=\"audio-5461-51\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5060.mp3?_=51\" \/><a href=\"https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5060.mp3\">https:\/\/keelungpass.com\/wp-content\/uploads\/2023\/07\/\u516b\u6597\u5b5060.mp3<\/a><\/audio><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0371e9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0371e9d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d2ac85d\" data-id=\"d2ac85d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c3716e elementor-align-right elementor-widget elementor-widget-button\" data-id=\"1c3716e\" data-element_type=\"widget\" id=\"turn back part BZ\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Return to playlist<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70ca0c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70ca0c0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32c44a9\" data-id=\"32c44a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f941b5 elementor-widget elementor-widget-text-editor\" data-id=\"2f941b5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\"><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/2600.svg\" alt=\"\u2600\" title=\"\">\u6211\u5011\u7684\u4f4d\u7f6e\u5728\u9019<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48aa89b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48aa89b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ad295f0\" data-id=\"ad295f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9ec7ce elementor-widget elementor-widget-google_maps\" data-id=\"a9ec7ce\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=%E5%85%AB%E6%96%97%E5%AD%90%E7%94%A2%E6%A5%AD%E4%BF%83%E9%80%B2%E6%9C%83&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"\u516b\u6597\u5b50\u7522\u696d\u4fc3\u9032\u6703\"\n\t\t\t\t\taria-label=\"\u516b\u6597\u5b50\u7522\u696d\u4fc3\u9032\u6703\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-02246ba\" data-id=\"02246ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd9cc92 elementor-widget elementor-widget-google_maps\" data-id=\"dd9cc92\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=%E5%A4%A7%E5%9D%AA%E6%B5%B7%E5%B2%B8&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Daping Shore\"\n\t\t\t\t\taria-label=\"Daping Shore\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-081df0d\" data-id=\"081df0d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-906e494 elementor-widget elementor-widget-google_maps\" data-id=\"906e494\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=%E5%9F%BA%E9%9A%86%E6%B5%B7%E7%A7%91%E9%A4%A8&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"\u57fa\u9686\u6d77\u79d1\u9928\"\n\t\t\t\t\taria-label=\"\u57fa\u9686\u6d77\u79d1\u9928\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\ud83c\udfa3\ud83c\udfa3Badouzi Fishing Village Walk\ud83c\udfa3\ud83c\udfa3 \u6d77\u79d1\u9928\u8207\u516b\u6597\u5b50\u80cc\u666f\u4ecb\u7d39 \u85cd\u6d77\u5de5\u4f5c\u574a\u4ecb\u7d39 ~\ud83c\udf60 &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/keelungpass.com\/english\/route3-en\/\"> <span class=\"screen-reader-text\">route3 Badouzi Fishing Village(en)<\/span> Read More &raquo;<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-5461","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/keelungpass.com\/english\/wp-json\/wp\/v2\/pages\/5461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keelungpass.com\/english\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/keelungpass.com\/english\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/keelungpass.com\/english\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/keelungpass.com\/english\/wp-json\/wp\/v2\/comments?post=5461"}],"version-history":[{"count":5,"href":"https:\/\/keelungpass.com\/english\/wp-json\/wp\/v2\/pages\/5461\/revisions"}],"predecessor-version":[{"id":15434,"href":"https:\/\/keelungpass.com\/english\/wp-json\/wp\/v2\/pages\/5461\/revisions\/15434"}],"wp:attachment":[{"href":"https:\/\/keelungpass.com\/english\/wp-json\/wp\/v2\/media?parent=5461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}